{"id":23479,"date":"2025-12-12T13:09:09","date_gmt":"2025-12-12T21:09:09","guid":{"rendered":"https:\/\/extension.wsu.edu\/pierce\/?post_type=tribe_events&#038;p=23479"},"modified":"2025-12-12T14:53:42","modified_gmt":"2025-12-12T22:53:42","slug":"fall-fest-seed-saving","status":"publish","type":"tribe_events","link":"https:\/\/extension.wsu.edu\/pierce\/event\/fall-fest-seed-saving\/","title":{"rendered":"Fall Fest &#8211; Seed Saving"},"content":{"rendered":"<div class=\"tribe-events-schedule tribe-clearfix\">\n\t<h2 class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\tSeptember 26\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t @ \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t10:00 am\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t11:30 am\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/h2>\n<\/div>\n\n\n\n<p>Theme: <em>Learn about and collect seeds from plants to save for future planting<\/em>.<br>We will provide more workshop detail as the date approaches. We just wanted to give you a feel of what\u2019s coming so you can add it to your calendar if you are interested.<br>Note: \u2018Day of\u2019 registration starts at 9:30am<\/p>\n\n\n<div class=\"tribe-block tribe-block__event-price\">\n\t\t<\/div>\n\n\n<div class=\"tribe-block tribe-block__organizer__details tribe-clearfix\">\n\t<div class=\"tribe-block__organizer__title\">\n\t\t<h3><a href=\"https:\/\/extension.wsu.edu\/pierce\/organizer\/youth-gardening\/\" title=\"Youth Gardening\" target=\"_self\" rel=\"\">Youth Gardening<\/a><\/h3>\n\t<\/div>\n\t\t\t\t<p class=\"tribe-block__organizer__website\"><a href=\"https:\/\/extension.wsu.edu\/pierce\/mg-home\/educational-outreach\/youth-gardening\/\" target=\"_self\" rel=\"external\">View Organizer Website<\/a><\/p>\n\t\t<\/div>\n\n\n<div class=\"tribe-block tribe-block__venue tribe-block__venue--has-map\">\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3><a href=\"https:\/\/extension.wsu.edu\/pierce\/venue\/puyallup-demonstrate-garden\/\" title=\"Puyallup Demonstration Garden\">Puyallup Demonstration Garden<\/a><\/h3>\n\t<\/div>\n\n\t\n\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">2607 West Pioneer<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Puyallup<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\t<abbr class=\"tribe-region tribe-events-abbr\" title=\"Washington\">WA<\/abbr>\n\n\t<span class=\"tribe-postal-code\">98371<\/span>\n\n\t<span class=\"tribe-country-name\">United States<\/span>\n\n<\/span>\n\n\t\t\t\t\t\t\t<a class=\"tribe-events-gmap\" href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=47.19116%2C-122.3264\" title=\"Click to view a Google Map\" target=\"_blank\" rel=\"noreferrer noopener\">+ Google Map<\/a>\t\t\t\t\t<\/address>\n\t\n\t\n\t\n\t<\/div>\n\t\n<div class=\"tribe-block__venue__map\">\n\t\n<iframe loading=\"lazy\"\n  title=\"Google maps iframe displaying the address to Puyallup Demonstration Garden\"\n  aria-label=\"Venue location map\"\n  width=\"100%\"\n  height=\"350px\"\n  frameborder=\"0\" style=\"border:0\"\n  src=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyDNsicAsP6-VuGtAb1O9riI3oc_NOb7IOU&#038;q=2607+West+Pioneer+Puyallup+WA+98371+United+States+&#038;zoom=10\" allowfullscreen>\n<\/iframe>\n<\/div>\n\n\t<\/div>\n\n\n\n\n\t<div class=\"tribe-block tribe-block__events-link\">\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\"  viewBox=\"0 0 23 17\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n  <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n  <path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button class=\"tribe-events-c-subscribe-dropdown__button-text\">\n\t\t\t\t\t\t\tAdd to calendar\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg  class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\"  viewBox=\"0 0 10 7\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/><\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\" tabindex=\"0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20260926T100000\/20260926T113000&#038;text=Fall%20Fest%20%26%238211%3B%20Seed%20Saving&#038;details=%3C%21--+wp%3Atribe%2Fevent-datetime+%2F--%3E%3C%21--+wp%3Aparagraph+%7B%22placeholder%22%3A%22Add+Description...%22%7D+--%3E%3Cp%3ETheme%3A+%3Cem%3ELearn+about+and+collect+seeds+from+plants+to+save+for+future+planting%3C%2Fem%3E.%3Cbr%3EWe+will+provide+more+workshop+detail+as+the+date+approaches.+We+just+wanted+to+give+you+a+feel+of+what%E2%80%99s+coming+so+you+can+add+it+to+your+calendar+if+you+are+interested.%3Cbr%3ENote%3A+%E2%80%98Day+of%E2%80%99+registration+starts+at+9%3A30am%3C%2Fp%3E%3C%21--+%2Fwp%3Aparagraph+--%3E%3C%21--+wp%3Atribe%2Fevent-price+%2F--%3E%3C%21--+wp%3Atribe%2Fevent-organizer+%7B%22organizer%22%3A20382%7D+%2F--%3E%3C%21--+wp%3Atribe%2Fevent-venue+%2F--%3E%3C%21--+wp%3Atribe%2Fevent-website+%2F--%3E%3C%21--+wp%3Atribe%2Fevent-links+%2F--%3E%3C%21--+wp%3Atribe%2Frelated-events+%2F--%3E&#038;location=Puyallup%20Demonstration%20Garden,%202607%20West%20Pioneer,%20Puyallup,%20WA,%2098371,%20United%20States&#038;trp=false&#038;ctz=America\/Los_Angeles&#038;sprop=website:https:\/\/extension.wsu.edu\/pierce\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Calendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<h2 class=\"tribe-block__related-events__title\">Related Events<\/h2>\n\n<ul class=\"tribe-related-events tribe-clearfix\">\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/extension.wsu.edu\/pierce\/event\/fall-in-the-rose-garden-more-fun-than-you-think\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/extension.wsu.edu\/pierce\/wp-content\/plugins\/events-calendar-pro\/src\/resources\/images\/tribe-related-events-placeholder.png\" alt=\"Fall in the Rose Garden: more fun than you think\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/extension.wsu.edu\/pierce\/event\/fall-in-the-rose-garden-more-fun-than-you-think\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tFall in the Rose Garden: more fun than you think\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">September 8 @ 5:30 pm<\/span> &#8211; <span class=\"tribe-event-time\">6:30 pm<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/extension.wsu.edu\/pierce\/event\/bloom-101-gardeners-guide-to-growing-dahlias\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/extension.wsu.edu\/pierce\/wp-content\/plugins\/events-calendar-pro\/src\/resources\/images\/tribe-related-events-placeholder.png\" alt=\"Bloom 101: Gardeners Guide to growing Dahlias\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/extension.wsu.edu\/pierce\/event\/bloom-101-gardeners-guide-to-growing-dahlias\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tBloom 101: Gardeners Guide to growing Dahlias\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">September 12 @ 10:00 am<\/span> &#8211; <span class=\"tribe-event-time\">11:00 am<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/extension.wsu.edu\/pierce\/event\/bulb-lasagna\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/extension.wsu.edu\/pierce\/wp-content\/plugins\/events-calendar-pro\/src\/resources\/images\/tribe-related-events-placeholder.png\" alt=\"Bulb Lasagna\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/extension.wsu.edu\/pierce\/event\/bulb-lasagna\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tBulb Lasagna\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">September 12 @ 2:00 pm<\/span> &#8211; <span class=\"tribe-event-time\">3:30 pm<\/span><\/div>\n<\/li>\n\t<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Theme: Learn about and collect seeds from plants to save for future planting.We will provide more workshop detail as the date approaches. We just wanted to give you a feel [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tec_requires_first_save":false,"_mi_skip_tracking":false,"_wsuwp_accessibility_report":[],"_EventAllDay":false,"_EventTimezone":"America\/Los_Angeles","_EventStartDate":"2026-09-26 10:00:00","_EventEndDate":"2026-09-26 11:30:00","_EventStartDateUTC":"2026-09-26 17:00:00","_EventEndDateUTC":"2026-09-26 18:30:00","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" @ ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[20382],"_EventVenueID":4190,"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":""},"tags":[31],"tribe_events_cat":[32],"_links":{"self":[{"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/tribe_events\/23479"}],"collection":[{"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/comments?post=23479"}],"version-history":[{"count":1,"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/tribe_events\/23479\/revisions"}],"predecessor-version":[{"id":23480,"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/tribe_events\/23479\/revisions\/23480"}],"wp:attachment":[{"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/media?parent=23479"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/tags?post=23479"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/extension.wsu.edu\/pierce\/wp-json\/wp\/v2\/tribe_events_cat?post=23479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}